{"id":13444,"date":"2023-08-18T15:10:17","date_gmt":"2023-08-18T12:10:17","guid":{"rendered":"https:\/\/corvusfirm.com\/komanda\/"},"modified":"2026-07-07T12:44:07","modified_gmt":"2026-07-07T09:44:07","slug":"komanda","status":"publish","type":"page","link":"https:\/\/corvusfirm.com\/ru\/komanda\/","title":{"rendered":"\u041a\u043e\u043c\u0430\u043d\u0434\u0430"},"content":{"rendered":"\n    <section id=\"hero-breadcrumbs-background-block_3c955f9c1f6bcd04f8536b9626636f40\" class=\"hero-breadcrumbs-background js-hero-breadcrumbs-background background-black-500\">\n        <div class=\"hero-breadcrumbs-background-wrapper container\">\n            <div class=\"row\">\n                <div class=\"col col-12 col-breadcrumbs js-fade-in\">\n                    <div class=\"col-wrapper\">\n                                            <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row row-content\">\n                <div class=\"col col-12 col-md-6 col-lg-auto col-left\">\n                    <div class=\"col-wrapper\">\n                        <h1 class=\"hero-breadcrumbs-background__title h1 js-fade-in\">\u041f\u043e\u0437\u043d\u0430\u043a\u043e\u043c\u044c\u0442\u0435\u0441\u044c \u0441 \u043a\u043e\u043c\u0430\u043d\u0434\u043e\u0439 \u043f\u0440\u043e\u0444\u0435\u0441\u0441\u0438\u043e\u043d\u0430\u043b\u043e\u0432 CORVUS  <\/h1>\n                        <p class=\"hero-breadcrumbs-background__desc-left js-fade-in\"><\/p>\n                    <\/div>\n                <\/div>\n                <div class=\"col col-12 col-md-6 col-lg-auto col-right\">\n                    <div class=\"col-wrapper js-fade-in\">\n                        <p class=\"hero-breadcrumbs-background__desc-right\"><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"animated-dots\">\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n            <span><\/span>\n        <\/div>\n        <div class=\"hero-breadcrumbs-background__background\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1374\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-scaled.jpg 2560w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-300x161.jpg 300w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-1024x549.jpg 1024w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-768x412.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-1536x824.jpg 1536w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-2048x1099.jpg 2048w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/09\/115D1A6246-1920x1030.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>        <\/div>\n    <\/section>\n\n<script>window.dispatchEvent( new Event('acf\/loaded\/hero-breadcrumbs-background'));<\/script>\n\n\n<section id=\"team-block_102d6e82f077617c26c17fe5cec3f9e0\" class=\"team js-team container-spacing-y-medium\">\n    <div class=\"team-wrapper container\">\n        <h2 class=\"team__sub-title js-fade-in\">\n            \u042e\u0420\u0418\u0414\u0418\u0427\u0415\u0421\u041a\u0410\u042f \u041f\u041e\u041c\u041e\u0429\u042c | \u0410\u0414\u0412\u041e\u041a\u0410\u0422\u042b         <\/h2>\n        <div class=\"row\">\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1983\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-scaled.jpg 1983w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-793x1024.jpg 793w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-768x991.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-1190x1536.jpg 1190w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-1587x2048.jpg 1587w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-36_2-837x1080.jpg 837w\" sizes=\"auto, (max-width: 1983px) 100vw, 1983px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0410\u043d\u0434\u0440\u0435\u0439 \u0412\u043e\u0440\u043e\u043d\u0446\u043e\u0432<\/h3>\n            <p class=\"card-role\">\u0423\u0447\u0440\u0435\u0434\u0438\u0442\u0435\u043b\u044c, \u041f\u0440\u0438\u0441\u044f\u0436\u043d\u044b\u0439 \u0430\u0434\u0432\u043e\u043a\u0430\u0442<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/andrejs-voroncovs\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0410\u043d\u0434\u0440\u0435\u0439 \u0412\u043e\u0440\u043e\u043d\u0446\u043e\u0432\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1983\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-scaled.jpg 1983w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-793x1024.jpg 793w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-768x991.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-1190x1536.jpg 1190w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-1587x2048.jpg 1587w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/08\/Vorontsov_juristi_04_26-71_2-5-837x1080.jpg 837w\" sizes=\"auto, (max-width: 1983px) 100vw, 1983px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041a\u0430\u043b\u0432\u0438\u0441 \u0412\u0430\u043d\u0430\u0433\u0441<\/h3>\n            <p class=\"card-role\">CAMS, \u0420\u0443\u043a\u043e\u0432\u043e\u0434\u044f\u0449\u0438\u0439 \u043f\u0430\u0440\u0442\u043d\u0435\u0440, \u041f\u0440\u0438\u0441\u044f\u0436\u043d\u044b\u0439 \u0430\u0434\u0432\u043e\u043a\u0430\u0442<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/kalvis-vanags\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041a\u0430\u043b\u0432\u0438\u0441 \u0412\u0430\u043d\u0430\u0433\u0441\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1765\" height=\"2271\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1.jpg 1765w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1-233x300.jpg 233w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1-796x1024.jpg 796w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1-768x988.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1-1194x1536.jpg 1194w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1-1592x2048.jpg 1592w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/11\/mb-1-839x1080.jpg 839w\" sizes=\"auto, (max-width: 1765px) 100vw, 1765px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041c\u0430\u0440\u0442\u044b\u043d\u044c\u0448 \u0411\u0438\u0440\u043a\u0441<\/h3>\n            <p class=\"card-role\">\u041f\u0440\u0438\u0441\u044f\u0436\u043d\u044b\u0439 \u0430\u0434\u0432\u043e\u043a\u0430\u0442<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/martins-birks\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041c\u0430\u0440\u0442\u044b\u043d\u044c\u0448 \u0411\u0438\u0440\u043a\u0441\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1986\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-scaled.jpg 1986w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-233x300.jpg 233w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-794x1024.jpg 794w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-768x990.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-1191x1536.jpg 1191w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-1589x2048.jpg 1589w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ip2-838x1080.jpg 838w\" sizes=\"auto, (max-width: 1986px) 100vw, 1986px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0418\u043d\u0442\u0430 \u041f\u0443\u0442\u0435\u043d\u0435<\/h3>\n            <p class=\"card-role\">\u041f\u0440\u0438\u0441\u044f\u0436\u043d\u044b\u0439 \u0430\u0434\u0432\u043e\u043a\u0430\u0442<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/inta-putene\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0418\u043d\u0442\u0430 \u041f\u0443\u0442\u0435\u043d\u0435\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1753\" height=\"2275\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1.jpg 1753w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1-231x300.jpg 231w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1-789x1024.jpg 789w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1-768x997.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1-1184x1536.jpg 1184w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1-1578x2048.jpg 1578w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vb1-832x1080.jpg 832w\" sizes=\"auto, (max-width: 1753px) 100vw, 1753px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0412\u0430\u043b\u0435\u0440\u0438\u044f \u0411\u0430\u0440\u044b\u0448\u043d\u0438\u043a\u043e\u0432\u0430<\/h3>\n            <p class=\"card-role\">\u041f\u0440\u0438\u0441\u044f\u0436\u043d\u044b\u0439 \u0430\u0434\u0432\u043e\u043a\u0430\u0442, Zv\u0113rin\u0101ta advok\u0101te<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/valerija-barisnikova\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0412\u0430\u043b\u0435\u0440\u0438\u044f \u0411\u0430\u0440\u044b\u0448\u043d\u0438\u043a\u043e\u0432\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1741\" height=\"2272\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1.jpg 1741w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1-785x1024.jpg 785w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1-768x1002.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1-1177x1536.jpg 1177w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1-1569x2048.jpg 1569w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/jm-1-828x1080.jpg 828w\" sizes=\"auto, (max-width: 1741px) 100vw, 1741px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u042f\u043d\u0438\u0441 \u041c\u0430\u0443\u043b\u0438\u0441<\/h3>\n            <p class=\"card-role\">\u041f\u043e\u043c\u043e\u0449\u043d\u0438\u043a \u043f\u0440\u0438\u0441\u044f\u0436\u043d\u043e\u0433\u043e \u0430\u0434\u0432\u043e\u043a\u0430\u0442\u0430<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/janis-maulis\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u042f\u043d\u0438\u0441 \u041c\u0430\u0443\u043b\u0438\u0441\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1983\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-scaled.jpg 1983w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-793x1024.jpg 793w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-768x991.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-1190x1536.jpg 1190w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-1587x2048.jpg 1587w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-191_2-837x1080.jpg 837w\" sizes=\"auto, (max-width: 1983px) 100vw, 1983px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0410\u0433\u043d\u0435\u0441\u0435 \u0413\u0443\u0434\u0435\u043b\u0435-\u041a\u0440\u043e\u043d\u0433\u043e\u0440\u043d\u0435<\/h3>\n            <p class=\"card-role\">\u041f\u043e\u043c\u043e\u0449\u043d\u0438\u0446\u0430 \u043f\u0440\u0438\u0441\u044f\u0436\u043d\u043e\u0433\u043e \u0430\u0434\u0432\u043e\u043a\u0430\u0442\u0430<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/agnese-gudele-krongorne\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0410\u0433\u043d\u0435\u0441\u0435 \u0413\u0443\u0434\u0435\u043b\u0435-\u041a\u0440\u043e\u043d\u0433\u043e\u0440\u043d\u0435\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1013\" height=\"1328\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ja7-3.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ja7-3.png 1013w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ja7-3-229x300.png 229w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ja7-3-781x1024.png 781w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ja7-3-768x1007.png 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ja7-3-824x1080.png 824w\" sizes=\"auto, (max-width: 1013px) 100vw, 1013px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u042e\u043b\u0438\u044f \u0410\u043b\u0435\u043a\u0441\u0435\u0435\u0432\u0430<\/h3>\n            <p class=\"card-role\">\u042e\u0440\u0438\u0441\u0442<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/julija-aleksejeva\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u042e\u043b\u0438\u044f \u0410\u043b\u0435\u043a\u0441\u0435\u0435\u0432\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1742\" height=\"2273\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika.jpg 1742w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika-785x1024.jpg 785w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika-768x1002.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika-1177x1536.jpg 1177w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika-1570x2048.jpg 1570w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/vika-828x1080.jpg 828w\" sizes=\"auto, (max-width: 1742px) 100vw, 1742px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0412\u0438\u043a\u0442\u043e\u0440\u0438\u044f \u0421\u0443\u0432\u043e\u0440\u043e\u0432\u0430<\/h3>\n            <p class=\"card-role\">\u041f\u043e\u043c\u043e\u0449\u043d\u0438\u0446\u0430 \u044e\u0440\u0438\u0441\u0442\u0430, \u0410\u0434\u043c\u0438\u043d\u0438\u0441\u0442\u0440\u0430\u0442\u043e\u0440 \u0411\u044e\u0440\u043e<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/viktorija-suvorova\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0412\u0438\u043a\u0442\u043e\u0440\u0438\u044f \u0421\u0443\u0432\u043e\u0440\u043e\u0432\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n<script>window.dispatchEvent( new Event('acf\/loaded\/team'));<\/script>\n\n\n<section id=\"team-block_693635bed29d45aea9eeeb4594f8113a\" class=\"team js-team container-spacing-y-medium\">\n    <div class=\"team-wrapper container\">\n        <h2 class=\"team__sub-title js-fade-in\">\n            \u0411\u0423\u0425\u0413\u0410\u041b\u0422\u0415\u0420\u0418\u042f | \u0410\u0423\u0414\u0418\u0422 | \u041a\u0410\u041f\u0418\u0422\u0410\u041b        <\/h2>\n        <div class=\"row\">\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1739\" height=\"2271\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2.jpg 1739w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2-784x1024.jpg 784w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2-768x1003.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2-1176x1536.jpg 1176w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2-1568x2048.jpg 1568w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-2-827x1080.jpg 827w\" sizes=\"auto, (max-width: 1739px) 100vw, 1739px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041a\u0438\u0440\u0438\u043b\u043b \u041a\u043e\u043d\u0434\u0440\u0430\u0442\u043e\u0432<\/h3>\n            <p class=\"card-role\">\u041f\u0440\u0438\u0441\u044f\u0436\u043d\u044b\u0439 \u0430\u0443\u0434\u0438\u0442\u043e\u0440, \u041f\u0430\u0440\u0442\u043d\u0435\u0440, \u0421\u0435\u0440\u0442\u0438\u0444\u0438\u0446\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0439 \u043d\u0430\u043b\u043e\u0433\u043e\u0432\u044b\u0439 \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442, CAMS<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/kirils-kondratovs\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041a\u0438\u0440\u0438\u043b\u043b \u041a\u043e\u043d\u0434\u0440\u0430\u0442\u043e\u0432\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1983\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-scaled.jpg 1983w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-793x1024.jpg 793w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-768x991.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-1190x1536.jpg 1190w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-1586x2048.jpg 1586w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/Vorontsov_juristi_04_26-302_2-1-837x1080.jpg 837w\" sizes=\"auto, (max-width: 1983px) 100vw, 1983px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041b\u044e\u0434\u043c\u0438\u043b\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u0447\u0443\u043a<\/h3>\n            <p class=\"card-role\">\u041f\u0430\u0440\u0442\u043d\u0451\u0440, \u041f\u043e\u043c\u043e\u0449\u043d\u0438\u0446\u0430 \u043f\u0440\u0438\u0441\u044f\u0436\u043d\u043e\u0433\u043e \u0430\u0443\u0434\u0438\u0442\u043e\u0440\u0430, \u0421\u0435\u0440\u0442\u0438\u0444\u0438\u0446\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0439 \u043d\u0430\u043b\u043e\u0433\u043e\u0432\u044b\u0439 \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442, \u0420\u0443\u043a\u043e\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440\u0441\u043a\u043e\u0433\u043e \u043e\u0442\u0434\u0435\u043b\u0430<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/ludmila-grebencuka\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041b\u044e\u0434\u043c\u0438\u043b\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u0447\u0443\u043a\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1997\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-scaled.jpg 1997w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-234x300.jpg 234w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-799x1024.jpg 799w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-768x984.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-1198x1536.jpg 1198w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-1598x2048.jpg 1598w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/VoroncovJuristi_09_24-292_3-2-843x1080.jpg 843w\" sizes=\"auto, (max-width: 1997px) 100vw, 1997px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0418\u043b\u043e\u043d\u0430 \u0421\u044b\u0447\u0430<\/h3>\n            <p class=\"card-role\">\u041f\u043e\u043c\u043e\u0449\u043d\u0438\u0446\u0430 \u043f\u0440\u0438\u0441\u044f\u0436\u043d\u043e\u0433\u043e \u0430\u0443\u0434\u0438\u0442\u043e\u0440\u0430<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/ilona-sica\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0418\u043b\u043e\u043d\u0430 \u0421\u044b\u0447\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1741\" height=\"2272\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1.jpg 1741w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1-785x1024.jpg 785w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1-768x1002.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1-1177x1536.jpg 1177w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1-1569x2048.jpg 1569w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ls1-828x1080.jpg 828w\" sizes=\"auto, (max-width: 1741px) 100vw, 1741px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041b\u0430\u0443\u0440\u0430 \u0421\u0442\u0440\u0430\u0443\u043c\u0435<\/h3>\n            <p class=\"card-role\">\u0421\u0442\u0430\u0440\u0448\u0438\u0439 \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440, \u0421\u0435\u0440\u0442\u0438\u0444\u0438\u0446\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0439 \u043d\u0430\u043b\u043e\u0433\u043e\u0432\u044b\u0439 \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442, Zverin\u0101ta revidenta pal\u012bdze<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/laura-straume\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041b\u0430\u0443\u0440\u0430 \u0421\u0442\u0440\u0430\u0443\u043c\u0435\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1736\" height=\"2271\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1.jpg 1736w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1-229x300.jpg 229w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1-783x1024.jpg 783w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1-768x1005.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1-1174x1536.jpg 1174w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1-1566x2048.jpg 1566w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ir1-826x1080.jpg 826w\" sizes=\"auto, (max-width: 1736px) 100vw, 1736px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0418\u0440\u0438\u043d\u0430 \u0420\u044b\u0431\u043a\u0438\u043d\u0430<\/h3>\n            <p class=\"card-role\">\u0421\u0442\u0430\u0440\u0448\u0438\u0439 \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/irina-ribkina\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0418\u0440\u0438\u043d\u0430 \u0420\u044b\u0431\u043a\u0438\u043d\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1962\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-scaled.jpg 1962w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-785x1024.jpg 785w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-768x1002.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-1177x1536.jpg 1177w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-1570x2048.jpg 1570w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/bc4pg-7-828x1080.jpg 828w\" sizes=\"auto, (max-width: 1962px) 100vw, 1962px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0411\u0430\u0439\u0431\u0430 \u0426\u0435\u043b\u043c\u0438\u043d\u044f<\/h3>\n            <p class=\"card-role\">\u0421\u0442\u0430\u0440\u0448\u0438\u0439 \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/baiba-celmina\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0411\u0430\u0439\u0431\u0430 \u0426\u0435\u043b\u043c\u0438\u043d\u044f\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1983\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-scaled.jpg 1983w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-793x1024.jpg 793w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-768x991.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-1190x1536.jpg 1190w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-1587x2048.jpg 1587w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/Vorontsov_juristi_04_26-174_2-837x1080.jpg 837w\" sizes=\"auto, (max-width: 1983px) 100vw, 1983px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u042e\u043b\u0438\u044f \u041b\u0430\u0432\u0440\u0435\u043d\u043a\u043e\u0432\u0430<\/h3>\n            <p class=\"card-role\">\u0421\u0442\u0430\u0440\u0448\u0438\u0439 \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/julija-lavrenkova\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u042e\u043b\u0438\u044f \u041b\u0430\u0432\u0440\u0435\u043d\u043a\u043e\u0432\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1966\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-scaled.jpg 1966w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-786x1024.jpg 786w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-768x1000.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-1180x1536.jpg 1180w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-1573x2048.jpg 1573w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2024\/10\/olga1-3-829x1080.jpg 829w\" sizes=\"auto, (max-width: 1966px) 100vw, 1966px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041e\u043b\u044c\u0433\u0430 \u041a\u0430\u0437\u0430\u0440\u044f\u043d<\/h3>\n            <p class=\"card-role\">\u0411\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/olga-kazarjana\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041e\u043b\u044c\u0433\u0430 \u041a\u0430\u0437\u0430\u0440\u044f\u043d\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1742\" height=\"2273\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3.jpg 1742w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3-785x1024.jpg 785w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3-768x1002.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3-1177x1536.jpg 1177w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3-1570x2048.jpg 1570w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/5-3-828x1080.jpg 828w\" sizes=\"auto, (max-width: 1742px) 100vw, 1742px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0410\u0439\u044f \u0412\u0438\u0442\u043e\u043b\u0430<\/h3>\n            <p class=\"card-role\">\u0411\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/aija-vitola\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0410\u0439\u044f \u0412\u0438\u0442\u043e\u043b\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n<script>window.dispatchEvent( new Event('acf\/loaded\/team'));<\/script>\n\n\n<section id=\"team-block_dcd04be04535a5624d62f1ec494c89ae\" class=\"team js-team container-spacing-y-medium\">\n    <div class=\"team-wrapper container\">\n        <h2 class=\"team__sub-title js-fade-in\">\n            \u041a\u041e\u041d\u0421\u0423\u041b\u042c\u0422\u0410\u041d\u0422\u042b | \u041f\u0410\u0420\u0422\u041d\u0415\u0420\u042b \u041f\u041e \u0421\u041e\u0422\u0420\u0423\u0414\u041d\u0418\u0427\u0415\u0421\u0422\u0412\u0423        <\/h2>\n        <div class=\"row\">\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1978\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-scaled.jpg 1978w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-791x1024.jpg 791w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-768x994.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-1187x1536.jpg 1187w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-1583x2048.jpg 1583w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2025\/08\/VoroncovPortraits_06_25-194_2-2-835x1080.jpg 835w\" sizes=\"auto, (max-width: 1978px) 100vw, 1978px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041e\u043b\u0435\u0433 \u0424\u0438\u043b\u0430\u0442\u043e\u0432<\/h3>\n            <p class=\"card-role\">\u0418\u0441\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u0434\u0438\u0440\u0435\u043a\u0442\u043e\u0440<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/oleg-filatov\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041e\u043b\u0435\u0433 \u0424\u0438\u043b\u0430\u0442\u043e\u0432\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1983\" height=\"2560\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-scaled.jpg 1983w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-232x300.jpg 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-793x1024.jpg 793w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-768x991.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-1190x1536.jpg 1190w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-1587x2048.jpg 1587w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/06\/iz-837x1080.jpg 837w\" sizes=\"auto, (max-width: 1983px) 100vw, 1983px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0418\u0440\u0438\u043d\u0430 \u0416\u0435\u0431\u0447\u0443\u043a<\/h3>\n            <p class=\"card-role\">\u0421\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043f\u0430\u0440\u0442\u043d\u0451\u0440 \u0432 \u0441\u0444\u0435\u0440\u0435 \u043c\u0430\u0440\u043a\u0435\u0442\u0438\u043d\u0433\u0430<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/irina-zebcuk\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0418\u0440\u0438\u043d\u0430 \u0416\u0435\u0431\u0447\u0443\u043a\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"1324\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-6-\u0438\u044e\u043b.-2026-\u0433.-13_48_37-2.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-6-\u0438\u044e\u043b.-2026-\u0433.-13_48_37-2.png 1023w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-6-\u0438\u044e\u043b.-2026-\u0433.-13_48_37-2-232x300.png 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-6-\u0438\u044e\u043b.-2026-\u0433.-13_48_37-2-791x1024.png 791w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-6-\u0438\u044e\u043b.-2026-\u0433.-13_48_37-2-768x994.png 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-6-\u0438\u044e\u043b.-2026-\u0433.-13_48_37-2-834x1080.png 834w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u041c\u0430\u0440\u0438\u044f \u041a\u0430\u043b\u043c\u044b\u043a\u043e\u0432\u0430<\/h3>\n            <p class=\"card-role\">\u0420\u0443\u043a\u043e\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c \u043f\u0440\u043e\u0435\u043a\u0442\u043e\u0432<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/marija-kalmikova\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u041c\u0430\u0440\u0438\u044f \u041a\u0430\u043b\u043c\u044b\u043a\u043e\u0432\u0430\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1740\" height=\"2271\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae.jpg 1740w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae-230x300.jpg 230w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae-785x1024.jpg 785w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae-768x1002.jpg 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae-1177x1536.jpg 1177w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae-1569x2048.jpg 1569w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2023\/09\/ae-827x1080.jpg 827w\" sizes=\"auto, (max-width: 1740px) 100vw, 1740px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0410\u043b\u0435\u043a\u0441\u0435\u0439 \u0415\u043b\u0438\u0441\u0435\u0435\u0432<\/h3>\n            <p class=\"card-role\">Cilv\u0113kties\u012bbu eksperts<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/aleksejs-jelisejevs\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0410\u043b\u0435\u043a\u0441\u0435\u0439 \u0415\u043b\u0438\u0441\u0435\u0435\u0432\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                            <div class=\"col col-card col-6 col-md-4 col-xl-3 js-fade-in\">\n                    \n<article class=\"card card--team js-card-team js-card-team \">\n    <div class=\"card-wrapper\">\n        <div class=\"card-thumb\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1029\" height=\"1330\" src=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/DK-2-1.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/DK-2-1.png 1029w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/DK-2-1-232x300.png 232w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/DK-2-1-792x1024.png 792w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/DK-2-1-768x993.png 768w, https:\/\/corvusfirm.com\/wp-content\/uploads\/2026\/07\/DK-2-1-836x1080.png 836w\" sizes=\"auto, (max-width: 1029px) 100vw, 1029px\" \/>        <\/div>\n        <div class=\"card-content\">\n            <h3 class=\"card-title\">\u0414\u043c\u0438\u0442\u0440\u0438\u0439 \u041a\u0440\u0430\u0432\u0447\u0435\u043d\u043a\u043e<\/h3>\n            <p class=\"card-role\">IT \u0441\u043f\u0435\u0446\u0438\u0430\u043b\u0438\u0441\u0442<\/p>\n            <p class=\"card-link\">\u0411\u043e\u043b\u044c\u0448\u0435 <\/p>\n            <a href=\"https:\/\/corvusfirm.com\/ru\/komanda\/dmitry-kravchenko\/\" class=\"stretched-link\" aria-label=\"\u0411\u043e\u043b\u044c\u0448\u0435 o \u0414\u043c\u0438\u0442\u0440\u0438\u0439 \u041a\u0440\u0430\u0432\u0447\u0435\u043d\u043a\u043e\"><\/a>\n        <\/div>\n    <\/div>\n<\/article>                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n<script>window.dispatchEvent( new Event('acf\/loaded\/team'));<\/script>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13444","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/pages\/13444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/comments?post=13444"}],"version-history":[{"count":41,"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/pages\/13444\/revisions"}],"predecessor-version":[{"id":19468,"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/pages\/13444\/revisions\/19468"}],"wp:attachment":[{"href":"https:\/\/corvusfirm.com\/ru\/wp-json\/wp\/v2\/media?parent=13444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}